{"id":19062,"date":"2024-01-08T19:22:00","date_gmt":"2024-01-08T19:22:00","guid":{"rendered":"https:\/\/breakthrough-pt.com\/?p=19062"},"modified":"2024-02-19T19:41:56","modified_gmt":"2024-02-19T19:41:56","slug":"strength-training-tips-for-beginners","status":"publish","type":"post","link":"https:\/\/breakthrough-pt.com\/es\/blog\/strength-training-tips-for-beginners\/","title":{"rendered":"Consejos de entrenamiento de fuerza para principiantes"},"content":{"rendered":"<p class=\"wp-block-paragraph\"><em><strong>Escrito por Alex Corbett, PT, DPT<\/strong><\/em><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>\u00bfQui\u00e9n puede beneficiarse del entrenamiento de fuerza?&nbsp;<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Mark Bell acu\u00f1\u00f3 la frase: \u201cLa fuerza nunca es una debilidad. La debilidad nunca es una fortaleza\u201d. Todo el mundo puede encontrar valor en el entrenamiento de fuerza porque aporta valor en muchas dimensiones. Ya seas un adolescente o un adulto mayor, hay&nbsp;<em>al menos&nbsp;<\/em>una raz\u00f3n por la que el entrenamiento de fuerza te beneficiar\u00e1. Esta lista no es exhaustiva, pero a continuaci\u00f3n se presentan 10 beneficios del entrenamiento de fuerza:&nbsp;<\/p>\n\n\n\n<ol class=\"wp-block-list\">\n<li><strong>Mayor fuerza y potencia:<\/strong>&nbsp;El entrenamiento de fuerza no es s\u00f3lo para deportistas. Al mejorar la fuerza, las actividades diarias como subir escaleras, levantar cajas o llevar la compra se vuelven m\u00e1s manejables.&nbsp;<\/li>\n\n\n\n<li><strong>Mejor calidad del sue\u00f1o:<\/strong>&nbsp;En una reciente&nbsp;<a href=\"https:\/\/www.ahajournals.org\/doi\/10.1161\/circ.145.suppl_1.038\" target=\"_blank\" rel=\"noopener\">estudiar<\/a>, aquellos que realizaron un entrenamiento de fuerza constante durmieron mejor que aquellos que solo realizaron cardio o eran sedentarios.&nbsp;&nbsp;<\/li>\n\n\n\n<li><strong>Resiliencia mejorada y reducci\u00f3n de lesiones:<\/strong>&nbsp;Realizar regularmente un entrenamiento de resistencia hace que el cuerpo sea m\u00e1s resistente y menos propenso a sufrir lesiones de la vida cotidiana.&nbsp;&nbsp;<\/li>\n\n\n\n<li><strong>Mejor composici\u00f3n corporal:<\/strong>&nbsp;El entrenamiento de fuerza puede provocar una disminuci\u00f3n de la grasa corporal y un aumento de la masa muscular magra.&nbsp;<\/li>\n\n\n\n<li><strong>Funci\u00f3n cognitiva mejorada:<\/strong>&nbsp;<a href=\"https:\/\/www.ncbi.nlm.nih.gov\/pmc\/articles\/PMC6239135\/\" target=\"_blank\" rel=\"noopener\">Estudios<\/a>&nbsp;han demostrado que el entrenamiento de resistencia regular se correlaciona con una mayor funci\u00f3n cognitiva, independientemente de la edad.&nbsp;<\/li>\n\n\n\n<li><strong>Salud \u00f3sea mejorada:<\/strong>&nbsp;El entrenamiento de resistencia ayuda a aumentar la densidad \u00f3sea y reduce el riesgo de osteoporosis.&nbsp;<\/li>\n\n\n\n<li><strong>Mejor funci\u00f3n articular:<\/strong>&nbsp;Fortalecer los m\u00fasculos alrededor de las articulaciones proporciona un mejor soporte, mejora la movilidad, reduce el dolor y reduce el riesgo de lesiones.&nbsp;<\/li>\n\n\n\n<li><strong>Mejor salud del coraz\u00f3n:<\/strong>&nbsp;El entrenamiento de resistencia regular tiene beneficios cardiovasculares, como&nbsp;<a href=\"https:\/\/www.nature.com\/articles\/s41598-022-26583-3\" target=\"_blank\" rel=\"noopener\">presi\u00f3n arterial mejorada<\/a>&nbsp;y factores de riesgo reducidos para enfermedades card\u00edacas.&nbsp;<\/li>\n\n\n\n<li><strong>Sensibilidad mejorada a la insulina:<\/strong>&nbsp;El entrenamiento de resistencia mejora la capacidad del cuerpo para regular los niveles de az\u00facar en sangre, reduciendo el riesgo de diabetes tipo 2.&nbsp;<\/li>\n\n\n\n<li><strong>Reducci\u00f3n de estr\u00e9s:<\/strong>&nbsp;Realizar entrenamiento de resistencia puede reducir los niveles de estr\u00e9s y mejorar el estado de \u00e1nimo al promover la liberaci\u00f3n de endorfinas.&nbsp;<\/li>\n<\/ol>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Consejos para empezar&nbsp;<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Comenzar un nuevo r\u00e9gimen de entrenamiento de fuerza puede ser desalentador, pero no se preocupe, lo cubrimos con rutinas de muestra y consejos de expertos de un fisioterapeuta sobre:&nbsp;<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Creando un plan&nbsp;<\/li>\n\n\n\n<li>\u00bfCu\u00e1ntos d\u00edas por semana de entrenamiento de fuerza?&nbsp;<\/li>\n\n\n\n<li>Eligiendo tus ejercicios&nbsp;<\/li>\n\n\n\n<li>\u00bfCu\u00e1ntas repeticiones y series realizar?&nbsp;<\/li>\n\n\n\n<li>\u00bfCu\u00e1nto peso usar?&nbsp;<\/li>\n<\/ul>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Cree un plan y sea coherente&nbsp;<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La diferencia entre hacer ejercicio y entrenar es que entrenar requiere un objetivo y cada sesi\u00f3n tiene un prop\u00f3sito. Si su objetivo es tener piernas m\u00e1s fuertes, entonces su programa de entrenamiento de fuerza deber\u00eda reflejarlo. Lo ideal es planificar en qu\u00e9 consistir\u00e1 cada semana y sesi\u00f3n antes de comenzar la semana. Por ejemplo, podr\u00edas planificar ir al gimnasio los lunes y jueves y fijarte el objetivo de hacer 4 series de prensas de piernas cada d\u00eda.<\/p>\n\n\n\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-8f761849 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<figure class=\"wp-block-image size-full\"><a href=\"https:\/\/breakthrough-pt.com\/wp-content\/uploads\/sites\/25\/2024\/02\/Two-Days-a-Week.png\" target=\"_blank\" rel=\"noreferrer noopener\"><img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"994\" src=\"https:\/\/breakthrough-pt.com\/wp-content\/uploads\/sites\/25\/2024\/02\/Two-Days-a-Week.png\" alt=\"\" class=\"wp-image-19065\" srcset=\"https:\/\/breakthrough-pt.com\/wp-content\/uploads\/sites\/25\/2024\/02\/Two-Days-a-Week.png 768w, https:\/\/breakthrough-pt.com\/wp-content\/uploads\/sites\/25\/2024\/02\/Two-Days-a-Week-232x300.png 232w, https:\/\/breakthrough-pt.com\/wp-content\/uploads\/sites\/25\/2024\/02\/Two-Days-a-Week-9x12.png 9w\" sizes=\"auto, (max-width: 768px) 100vw, 768px\" \/><\/a><\/figure>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<figure class=\"wp-block-image size-full\"><a href=\"https:\/\/breakthrough-pt.com\/wp-content\/uploads\/sites\/25\/2024\/02\/Three-Days-a-Week.png\" target=\"_blank\" rel=\"noreferrer noopener\"><img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"994\" src=\"https:\/\/breakthrough-pt.com\/wp-content\/uploads\/sites\/25\/2024\/02\/Three-Days-a-Week.png\" alt=\"\" class=\"wp-image-19064\" srcset=\"https:\/\/breakthrough-pt.com\/wp-content\/uploads\/sites\/25\/2024\/02\/Three-Days-a-Week.png 768w, https:\/\/breakthrough-pt.com\/wp-content\/uploads\/sites\/25\/2024\/02\/Three-Days-a-Week-232x300.png 232w, https:\/\/breakthrough-pt.com\/wp-content\/uploads\/sites\/25\/2024\/02\/Three-Days-a-Week-9x12.png 9w\" sizes=\"auto, (max-width: 768px) 100vw, 768px\" \/><\/a><\/figure>\n<\/div>\n<\/div>\n\n\n\n<p class=\"wp-block-paragraph\">Planificar sus d\u00edas de entrenamiento y lo que quiere lograr ayuda a eliminar las dudas. Como fisioterapeuta, esta es una de las mayores barreras que veo para iniciar un r\u00e9gimen de ejercicios.&nbsp;<strong>Las personas que se apegan a un plan tienen m\u00e1s \u00e9xito que aquellas que intentan resolverlo a lo largo del camino.<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>\u00bfCu\u00e1ntos d\u00edas por semana de entrenamiento de fuerza?&nbsp;<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Esto se conoce como&nbsp;<strong>frecuencia<\/strong>, y existe evidencia sustancial de que el entrenamiento de fuerza entre 1 y 6 d\u00edas por semana puede aumentar su fuerza. Un plan de entrenamiento de mayor frecuencia tiene ventajas; sin embargo, todo se reduce a cu\u00e1ntos d\u00edas por semana puedes comprometerte.&nbsp;&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Para principiantes, aqu\u00ed est\u00e1 mi recomendaci\u00f3n:&nbsp;<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Empezar con<strong>&nbsp;1-3 d\u00edas por semana<\/strong>&nbsp;de entrenamiento de fuerza&nbsp;<strong>por grupo muscular<\/strong>.&nbsp;&nbsp;<\/li>\n<\/ul>\n\n\n\n<p class=\"wp-block-paragraph\">La cantidad de d\u00edas depende de lo que mejor se adapte a su horario y objetivos generales. Recuerde, \u00a1el mejor plan es aquel que puede seguir!&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Elegir tus ejercicios&nbsp;<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Puede resultar dif\u00edcil saber si utilizar m\u00e1quinas, mancuernas o barras cuando reci\u00e9n est\u00e1s empezando. La buena noticia es que no importa lo que uses. Elija aquello con lo que se sienta c\u00f3modo y sea constante en el uso de esa opci\u00f3n de resistencia. Si realiza con frecuencia pesas libres, m\u00e1quinas y ejercicios de peso corporal, resulta dif\u00edcil realizar un seguimiento del progreso.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Recomiendo que los principiantes elijan:&nbsp;<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>(1) ejercicio de empuje de la parte superior del cuerpo&nbsp;<\/li>\n\n\n\n<li>(1) ejercicio de tracci\u00f3n de la parte superior del cuerpo&nbsp;<\/li>\n\n\n\n<li>(1) ejercicio de la parte inferior del cuerpo&nbsp;<\/li>\n<\/ul>\n\n\n\n<p class=\"wp-block-paragraph\">Reducirlos a\u00fan m\u00e1s a ejercicios multiarticulares tambi\u00e9n le brindar\u00e1 el mejor rendimiento por su inversi\u00f3n.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Aqu\u00ed hay unos ejemplos:&nbsp;<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Ejercicios de empuje de la parte superior del cuerpo.&nbsp;<\/li>\n<\/ul>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Press de banca, press de pecho con m\u00e1quina, flexiones, press de hombros, fondos asistidos&nbsp;<\/li>\n\n\n\n<li>Ejercicios de tracci\u00f3n de la parte superior del cuerpo.&nbsp;<\/li>\n<\/ul>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Remo con m\u00e1quina de cable, remo con mancuernas, dominadas laterales, dominadas asistidas&nbsp;<\/li>\n\n\n\n<li>ejercicios para la parte inferior del cuerpo&nbsp;<\/li>\n<\/ul>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Sentadillas, prensa de piernas, peso muerto, estocadas, empujes de cadera&nbsp;<\/li>\n<\/ul>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>\u00bfCu\u00e1ntas repeticiones hacer?&nbsp;<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Nota r\u00e1pida: una repetici\u00f3n (rep) se refiere a un solo movimiento, mientras que una serie se refiere a cu\u00e1ntas series separadas de repeticiones se realizan. Por ejemplo, si haces 10 sentadillas seguidas, te tomas un minuto de descanso y luego haces otras 10 sentadillas, habr\u00e1s hecho 2 series de 10 repeticiones.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La cantidad de repeticiones que debes realizar est\u00e1 inversamente relacionada con el peso que est\u00e1s usando. En pocas palabras, cuanto m\u00e1s peso levantes, menos repeticiones podr\u00e1s hacer.&nbsp;&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Mi recomendaci\u00f3n:&nbsp;<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Llevar a cabo<strong>&nbsp;3-5 repeticiones<\/strong>&nbsp;por set si tu objetivo es&nbsp;<strong>fuerza solamente.<\/strong>&nbsp;<\/li>\n\n\n\n<li>Llevar a cabo<strong>&nbsp;6-15 repeticiones<\/strong>&nbsp;si tu objetivo es una mezcla de<strong>&nbsp;fuerza y musculo<\/strong>&nbsp;edificio.&nbsp;<\/li>\n<\/ul>\n\n\n\n<p class=\"wp-block-paragraph\">El desarrollo muscular puro tiene un&nbsp;<a href=\"https:\/\/www.ncbi.nlm.nih.gov\/pmc\/articles\/PMC8449772\/\" target=\"_blank\" rel=\"noopener\">rango m\u00e1s grande<\/a>&nbsp;de oportunidad (6-40 repeticiones realizadas cerca del fallo), pero a medida que te alejas del rango de repeticiones m\u00e1s bajo, tus ganancias de fuerza comienzan a disminuir.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Esta recomendaci\u00f3n tiene en cuenta dos cosas principales:&nbsp;<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Un peso muy pesado, cercano al m\u00e1ximo de 1 o 2 repeticiones, tiende a ser m\u00e1s duro para las articulaciones. El uso frecuente de este rango tiende a hacer que las personas sientan dolor.&nbsp;&nbsp;<\/li>\n\n\n\n<li>A medida que comienzas a superar las 15 repeticiones, te adentras en un territorio que comienza a limitar las ganancias de fuerza. Imag\u00ednese hacer curl con un peso de dos libras durante 100 repeticiones; no aumentar\u00e1 la fuerza de sus b\u00edceps con este enfoque.&nbsp;<\/li>\n<\/ul>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>\u00bfCu\u00e1ntas series hacer?&nbsp;<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Aspirar a&nbsp;<strong>3-15 series<\/strong>&nbsp;de un ejercicio&nbsp;<strong>por semana<\/strong>. Este es un rango amplio determinado en parte por la frecuencia de ejercicio y los niveles de condici\u00f3n f\u00edsica actuales.&nbsp;&nbsp;<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Ejemplo: tu objetivo es realizar 9 series de prensas de piernas cada semana para mejorar la fuerza de tus piernas.&nbsp;<\/li>\n<\/ul>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Si entrenas 3 d\u00edas a la semana, realizar\u00e1s 3 series en cada sesi\u00f3n.&nbsp;<\/li>\n\n\n\n<li>Si entrenas 2 d\u00edas a la semana, realizar\u00e1s de 4 a 5 series en cada sesi\u00f3n.&nbsp;<\/li>\n\n\n\n<li>Si entrenas 1 d\u00eda a la semana, realizar\u00e1s 9 series en una sesi\u00f3n.&nbsp;<\/li>\n<\/ul>\n\n\n\n<p class=\"wp-block-paragraph\">Para los principiantes, una de esas opciones ser\u00e1 dif\u00edcil de manejar. Realizar 9 series de prensas de piernas en una sesi\u00f3n llevar\u00e1 mucho tiempo y te har\u00e1&nbsp;<em>muy adolorido.<\/em>&nbsp;&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Como puedes ver, es una ventaja distribuir tus series semanales en varios d\u00edas. Sin embargo, si tiene poco tiempo y solo puede levantar pesas una vez por semana, le recomiendo comenzar con 3 a 5 series m\u00e1s bajas y luego ir subiendo lentamente con el tiempo a medida que su cuerpo se aclimata.&nbsp;&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>\u00bfCu\u00e1nto peso usar?&nbsp;<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La respuesta r\u00e1pida que no requiere pruebas m\u00e1ximas ni f\u00f3rmulas matem\u00e1ticas reside en un concepto llamado \u201crepresentantes en reserva\u201d (RIR). La base de RIR implica elegir una resistencia que sea desafiante hasta el punto de que puedas realizar, como m\u00e1ximo, 2 o 3 repeticiones m\u00e1s que la serie prevista. En una escala de esfuerzo de 0 a 10, esto deber\u00eda rondar el 7-8\/10.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">A continuaci\u00f3n se muestran ejemplos de c\u00f3mo elegir un peso o nivel de resistencia para un ejercicio de 10 repeticiones:&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Muy ligero<\/strong>&nbsp;<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Realizas 10 repeticiones con dificultad moderada y sientes que podr\u00edas realizar 5 o m\u00e1s repeticiones adicionales.&nbsp;<\/li>\n<\/ul>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Muy pesado<\/strong>&nbsp;<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Te cuesta llegar a 6 repeticiones; O tu forma se rompe o no puedes completar las 4 repeticiones restantes.&nbsp;<\/li>\n<\/ul>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Solo bien<\/strong>&nbsp;<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Te cuesta llegar a 8 repeticiones y las \u00faltimas 2 son muy desafiantes. Podr\u00edas haber hecho 2 m\u00e1s si lo hubieras presionado.&nbsp;<\/li>\n<\/ul>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Consejo de experto:&nbsp;<\/strong>Al comenzar y cada pocas semanas despu\u00e9s, recomiendo probar tu m\u00e1ximo de manera segura en cada ejercicio. En mi experiencia, los principiantes son conocidos por subestimar cu\u00e1ntas repeticiones pueden realizar. A menudo pido a pacientes que realicen una serie de 10 y me informan que podr\u00edan haber hecho 1 o 2 repeticiones m\u00e1s. Sin embargo, cuando prueban su m\u00e1ximo en la siguiente serie, a menudo pueden realizar m\u00e1s de 20 repeticiones.&nbsp;<\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><a href=\"https:\/\/goconfluent.com\/physical-therapy-near-me\/\" target=\"_blank\" rel=\"noreferrer noopener\"><img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"152\" src=\"https:\/\/breakthrough-pt.com\/wp-content\/uploads\/sites\/25\/2024\/01\/Blog-CTA.jpg\" alt=\"\" class=\"wp-image-19016\" srcset=\"https:\/\/breakthrough-pt.com\/wp-content\/uploads\/sites\/25\/2024\/01\/Blog-CTA.jpg 800w, https:\/\/breakthrough-pt.com\/wp-content\/uploads\/sites\/25\/2024\/01\/Blog-CTA-300x57.jpg 300w, https:\/\/breakthrough-pt.com\/wp-content\/uploads\/sites\/25\/2024\/01\/Blog-CTA-768x146.jpg 768w, https:\/\/breakthrough-pt.com\/wp-content\/uploads\/sites\/25\/2024\/01\/Blog-CTA-18x3.jpg 18w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><\/a><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\"><br><strong>\u00bfC\u00f3mo puede ayudar un fisioterapeuta?&nbsp;<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u00bfAlguna vez ha visitado un restaurante que ten\u00eda un men\u00fa con varias p\u00e1ginas de platos principales y complementos? Elegir una comida puede resultar abrumador, similar a lo que pueden sentir los principiantes cuando comienzan con el entrenamiento de fuerza. Si se tienen en cuenta las lesiones antiguas, la incertidumbre sobre la forma de hacer ejercicio y otras variables, de repente se siente como si estuviera tratando de encontrar un plato principal sin gluten en un men\u00fa extranjero.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Aqu\u00ed es donde su fisioterapeuta puede ayudarle. Su fisioterapeuta podr\u00e1 personalizar su rutina, ajustar su forma y asegurarse de que todo est\u00e9 adaptado a sus necesidades.&nbsp;<em>sus objetivos espec\u00edficos y su historial de lesiones.<\/em>&nbsp;Son su chef personal y su salvavidas para cualquier pregunta que tenga.&nbsp;<\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"642\" height=\"230\" src=\"https:\/\/breakthrough-pt.com\/wp-content\/uploads\/sites\/25\/2023\/11\/Screenshot-2023-11-20-at-10.34.41-AM-1.png\" alt=\"\" class=\"wp-image-18986\" srcset=\"https:\/\/breakthrough-pt.com\/wp-content\/uploads\/sites\/25\/2023\/11\/Screenshot-2023-11-20-at-10.34.41-AM-1.png 642w, https:\/\/breakthrough-pt.com\/wp-content\/uploads\/sites\/25\/2023\/11\/Screenshot-2023-11-20-at-10.34.41-AM-1-300x107.png 300w, https:\/\/breakthrough-pt.com\/wp-content\/uploads\/sites\/25\/2023\/11\/Screenshot-2023-11-20-at-10.34.41-AM-1-18x6.png 18w, https:\/\/breakthrough-pt.com\/wp-content\/uploads\/sites\/25\/2023\/11\/Screenshot-2023-11-20-at-10.34.41-AM-1-640x230.png 640w\" sizes=\"auto, (max-width: 642px) 100vw, 642px\" \/><\/figure>\n<\/div>\n\n\n<p class=\"has-text-align-center wp-block-paragraph\"><a href=\"https:\/\/breakthrough-pt.com\/es\/\">Fisioterapia innovadora<\/a><strong>, miembro de la familia Confluent Health<\/strong><\/p>","protected":false},"excerpt":{"rendered":"<p>Written by Alex Corbett, PT, DPT Who can benefit from strength training?&nbsp; Mark Bell coined the phrase, \u201cStrength is never a weakness. Weakness is never [&hellip;]<\/p>\n","protected":false},"author":6,"featured_media":19063,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[1],"tags":[],"class_list":["post-19062","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-uncategorized"],"acf":[],"jetpack_featured_media_url":"https:\/\/breakthrough-pt.com\/wp-content\/uploads\/sites\/25\/2024\/02\/87a4eae8-d504-49c4-b4f4-0364586ef483.jpeg","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/breakthrough-pt.com\/es\/wp-json\/wp\/v2\/posts\/19062","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/breakthrough-pt.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/breakthrough-pt.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/breakthrough-pt.com\/es\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/breakthrough-pt.com\/es\/wp-json\/wp\/v2\/comments?post=19062"}],"version-history":[{"count":0,"href":"https:\/\/breakthrough-pt.com\/es\/wp-json\/wp\/v2\/posts\/19062\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/breakthrough-pt.com\/es\/wp-json\/wp\/v2\/media\/19063"}],"wp:attachment":[{"href":"https:\/\/breakthrough-pt.com\/es\/wp-json\/wp\/v2\/media?parent=19062"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/breakthrough-pt.com\/es\/wp-json\/wp\/v2\/categories?post=19062"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/breakthrough-pt.com\/es\/wp-json\/wp\/v2\/tags?post=19062"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}