{"id":1671,"date":"2017-02-16T19:28:45","date_gmt":"2017-02-16T19:28:45","guid":{"rendered":"https:\/\/breakthroughpt.confluentclinics.com\/blog\/physical-therapists-guide-cancer\/"},"modified":"2017-02-16T19:28:45","modified_gmt":"2017-02-16T19:28:45","slug":"physical-therapists-guide-cancer","status":"publish","type":"post","link":"https:\/\/breakthrough-pt.com\/es\/blog\/physical-therapists-guide-cancer\/","title":{"rendered":"Gu\u00eda del fisioterapeuta sobre el c\u00e1ncer"},"content":{"rendered":"<p>El c\u00e1ncer es el crecimiento de c\u00e9lulas anormales en el cuerpo que causa la destrucci\u00f3n de c\u00e9lulas normales y sanas. Este proceso afecta la salud y el funcionamiento del cuerpo o partes del cuerpo y puede causar la muerte. El c\u00e1ncer afecta al 39,6% de personas en Estados Unidos (EE.UU.) en alg\u00fan momento de sus vidas, con m\u00e1s de 1,5 millones de nuevos casos diagnosticados cada a\u00f1o. Las muertes por c\u00e1ncer son mayores entre los hombres que entre las mujeres en los EE. UU.: las m\u00e1s altas entre los hombres afroamericanos y las m\u00e1s bajas entre las mujeres asi\u00e1ticas o de las islas del Pac\u00edfico. En todo el mundo, cada a\u00f1o se diagnostican aproximadamente 14 millones de nuevos casos de c\u00e1ncer y se registran 8,2 millones de muertes por c\u00e1ncer.<\/p>\n<p>El c\u00e1ncer y sus tratamientos pueden causar problemas f\u00edsicos como dolor, entumecimiento, hinchaz\u00f3n, debilidad, p\u00e9rdida del equilibrio y dificultad para moverse o caminar. Los fisioterapeutas ayudan a las personas a controlar los problemas relacionados con el c\u00e1ncer, mejorar su salud y sus capacidades funcionales y regresar al trabajo y a otras actividades.<\/p>\n<p>\u00bfQu\u00e9 es el c\u00e1ncer?<\/p>\n<p>El c\u00e1ncer es un crecimiento descontrolado de c\u00e9lulas anormales en el cuerpo. Las c\u00e9lulas anormales interfieren con las c\u00e9lulas normales y pueden diseminarse por todo el cuerpo.<\/p>\n<p>El c\u00e1ncer se diagnostica en adultos y ni\u00f1os. Puede afectar cualquier parte del cuerpo, incluidos \u00f3rganos, huesos y m\u00fasculos. Los tipos de c\u00e1ncer m\u00e1s comunes diagnosticados en los EE. UU. (en orden descendente) son:<\/p>\n<ul>\n<li>Mama<\/li>\n<li>Pulm\u00f3n<\/li>\n<li>Pr\u00f3stata<\/li>\n<li>Colon<\/li>\n<li>Vejiga<\/li>\n<li>Piel<\/li>\n<li>Tiroides<\/li>\n<\/ul>\n<p>Las tasas de mortalidad por c\u00e1ncer en Estados Unidos han disminuido desde principios de los a\u00f1os 1990; M\u00e1s estadounidenses que nunca sobreviven al c\u00e1ncer.<\/p>\n<p>El tratamiento convencional para el c\u00e1ncer incluye cirug\u00eda, quimioterapia, radiaci\u00f3n y terapia g\u00e9nica. El c\u00e1ncer y los efectos secundarios del tratamiento pueden causar problemas f\u00edsicos, como:<\/p>\n<ul>\n<li>Dolor<\/li>\n<li>Entumecimiento en pies y manos.<\/li>\n<li>Hinchaz\u00f3n de los ganglios linf\u00e1ticos (<a href=\"https:\/\/www.moveforwardpt.com\/symptomsconditionsdetail.aspx?cid=8fadc252-aa62-472d-9f22-977837a30acc\" target=\"_blank\" rel=\"noopener noreferrer\">linfedema<\/a>)<\/li>\n<li>Hinchaz\u00f3n de brazos, piernas, torso o cara.<\/li>\n<li>Debilidad muscular<\/li>\n<li>Rigidez articular<\/li>\n<li>Fatiga<\/li>\n<li>P\u00e9rdida de resistencia<\/li>\n<li>P\u00e9rdida de densidad \u00f3sea (fuerza)<\/li>\n<li>dificultad para caminar<\/li>\n<li>P\u00e9rdida del equilibrio<\/li>\n<li>Aumento de peso<\/li>\n<li>Niebla del cerebro<\/li>\n<li>Problemas del coraz\u00f3n<\/li>\n<\/ul>\n<div class=\"backTop\">Signos y s\u00edntomas<\/div>\n<div id=\"ctl00_ctl00_ctl00_PreContentAreaPlaceHolder_PreContentAreaPlaceHolder_WebPartManager1_wp416776347_ctl01_ctl00_pnlSignsAndSymptoms\">\n<p>A veces, el c\u00e1ncer no causa ning\u00fan signo ni s\u00edntoma y se descubre durante un examen o detecci\u00f3n m\u00e9dica.<\/p>\n<p>Los signos y s\u00edntomas comunes del c\u00e1ncer pueden incluir:<\/p>\n<p><strong>Se\u00f1ales:<\/strong><\/p>\n<ul>\n<li>P\u00e9rdida de peso inexplicable<\/li>\n<li>Sangrado inexplicable<\/li>\n<li>Cambios en la piel<\/li>\n<\/ul>\n<p><strong>S\u00edntomas:<\/strong><\/p>\n<ul>\n<li>Fiebre<\/li>\n<li>Fatiga<\/li>\n<li>Dolor<\/li>\n<li>Entumecimiento<\/li>\n<li>Tos persistente<\/li>\n<li>dolores de cabeza<\/li>\n<li>Problemas de la vista<\/li>\n<\/ul>\n<p>Puede encontrar m\u00e1s informaci\u00f3n sobre los signos y s\u00edntomas del c\u00e1ncer en el sitio web de la Sociedad Estadounidense del C\u00e1ncer.\u00a0<a href=\"https:\/\/www.cancer.org\/cancer\/cancerbasics\/signs-and-symptoms-of-cancer\" target=\"_blank\" rel=\"noopener\">sitio web<\/a>.<\/p>\n<div class=\"backTop\">\u00bfC\u00f3mo se diagnostica?<\/div>\n<\/div>\n<div id=\"ctl00_ctl00_ctl00_PreContentAreaPlaceHolder_PreContentAreaPlaceHolder_WebPartManager1_wp416776347_ctl01_ctl00_pnlHowIsItDiagnosed\">\n<p>El c\u00e1ncer lo diagnostica un m\u00e9dico. Un fisioterapeuta puede examinar a una persona a la que se le ha diagnosticado c\u00e1ncer en busca de problemas f\u00edsicos que causen malestar o dificultad con el movimiento. El examen de fisioterapia eval\u00faa la fuerza, la flexibilidad, el equilibrio, la sensaci\u00f3n, la coordinaci\u00f3n, la resistencia y la capacidad de una persona para caminar y moverse. Los fisioterapeutas crean planes de tratamiento especializados para abordar las necesidades y objetivos de las personas afectadas por el c\u00e1ncer.<\/p>\n<div class=\"backTop\">\u00bfC\u00f3mo puede ayudar un fisioterapeuta? Los fisioterapeutas est\u00e1n capacitados y educados para comprender todas sus afecciones de salud, incluido el diagn\u00f3stico de c\u00e1ncer. Su fisioterapeuta trabajar\u00e1 con usted para desarrollar un programa de tratamiento especializado que aborde sus necesidades y objetivos espec\u00edficos.<\/p>\n<p>La Sociedad Estadounidense del C\u00e1ncer recomienda que las personas que reciben tratamiento contra el c\u00e1ncer y los sobrevivientes de c\u00e1ncer realicen ejercicio f\u00edsico constante para disminuir la fatiga y mejorar la capacidad de realizar las actividades diarias normales. Los estudios demuestran que el ejercicio puede mejorar las posibilidades de que un individuo sobreviva al c\u00e1ncer. Los fisioterapeutas pueden dise\u00f1ar programas individualizados de ejercicio y tratamiento para reducir o prevenir muchos problemas relacionados con el c\u00e1ncer.<\/p>\n<p>Los fisioterapeutas ayudan a las personas diagnosticadas con c\u00e1ncer antes y despu\u00e9s de la cirug\u00eda. Antes de la cirug\u00eda, eval\u00faan a las personas para detectar cualquiera de los problemas enumerados anteriormente y ayudan a abordarlos. Despu\u00e9s de la cirug\u00eda, pueden ayudar con la curaci\u00f3n del sitio de la incisi\u00f3n, mejorar la circulaci\u00f3n, reducir el dolor y minimizar las cicatrices. Eval\u00faan a las personas para determinar cualquier necesidad de tratamiento de fisioterapia y, al dise\u00f1ar programas de tratamiento individualizados, las ayudan a recuperarse y sanar m\u00e1s r\u00e1pido de lo que lo har\u00edan por s\u00ed solas.<\/p>\n<p>Su fisioterapeuta puede trabajar con usted para mejorar su:<\/p>\n<p><strong>Comodidad y bienestar.\u00a0<\/strong>El c\u00e1ncer y los tratamientos contra el c\u00e1ncer pueden causar s\u00edntomas como dolor, sensaci\u00f3n de ardor, entumecimiento, hormigueo (neuropat\u00eda), calambres, espasmos y debilidad. Su fisioterapeuta puede aplicar t\u00e9cnicas pr\u00e1cticas (terapia manual) o tecnolog\u00edas como estimulaci\u00f3n el\u00e9ctrica para ayudar a disminuir el dolor y aliviar los s\u00edntomas. El fisioterapeuta podr\u00e1 ense\u00f1arle ejercicios suaves o t\u00e9cnicas para realizar en casa que le ayuden en su recuperaci\u00f3n. Todas estas opciones pueden reducir o eliminar la necesidad de analg\u00e9sicos opioides.<\/p>\n<p><strong>Capacidad aer\u00f3bica.\u00a0<\/strong>El c\u00e1ncer o el tratamiento contra el c\u00e1ncer pueden haber disminuido su capacidad para procesar ox\u00edgeno (capacidad aer\u00f3bica), provocando fatiga. Las investigaciones muestran que el ejercicio aer\u00f3bico, como caminar en una cinta rodante durante al menos 20 minutos 3 veces por semana, puede ayudar a mejorar la capacidad aer\u00f3bica, reducir la fatiga y optimizar la curaci\u00f3n. Su fisioterapeuta puede evaluar su capacidad aer\u00f3bica y determinar las mejores actividades aer\u00f3bicas para usted.<\/p>\n<p><strong>Densidad osea<\/strong>. La falta de actividad y ciertos tratamientos contra el c\u00e1ncer pueden provocar el debilitamiento de los huesos, lo que podr\u00eda provocar fracturas \u00f3seas. Ciertos tipos de ejercicio pueden prevenir la p\u00e9rdida \u00f3sea y mantener la fortaleza \u00f3sea. Su fisioterapeuta puede ense\u00f1arle ejercicios seguros y eficaces para ayudarle a desarrollar la fuerza \u00f3sea de manera constante.<\/p>\n<p><strong>Linfedema e hinchaz\u00f3n.<\/strong>\u00a0Ciertos tratamientos contra el c\u00e1ncer pueden provocar linfedema (hinchaz\u00f3n en brazos o piernas) u otros tipos de hinchaz\u00f3n. Su fisioterapeuta puede utilizar varios m\u00e9todos para reducir, controlar y prevenir el linfedema y la hinchaz\u00f3n, como masajes suaves especializados, movimientos y ejercicios especiales y la aplicaci\u00f3n de prendas compresivas como mangas para brazos, guantes y medias para piernas.<\/p>\n<p><strong>Incisiones quir\u00fargicas.\u00a0<\/strong>Su fisioterapeuta puede ayudarlo a cuidar las incisiones quir\u00fargicas y las \u00e1reas suturadas, verificando si hay infecciones y ayud\u00e1ndolo con los cambios de vendaje. El fisioterapeuta tambi\u00e9n puede ayudar a prevenir algunos tipos de cicatrices y tirantez de la piel a medida que cicatriza la l\u00ednea de sutura. Su fisioterapeuta puede utilizar masajes muy suaves o determinadas tecnolog\u00edas para mantener la piel lo m\u00e1s suave y flexible posible.<\/p>\n<p><strong>Peso corporal.\u00a0<\/strong>Al crear un programa de ejercicios y actividad f\u00edsica dise\u00f1ado exclusivamente para usted, su fisioterapeuta lo ayudar\u00e1 a reducir la grasa corporal y a mantener un peso corporal saludable, lo que puede mejorar sus niveles de energ\u00eda.<\/p>\n<p><strong>\u00c1nimo.<\/strong>\u00a0El ejercicio ayuda a mejorar el estado de \u00e1nimo y reducir la depresi\u00f3n en todas las personas, incluidos los pacientes y sobrevivientes de c\u00e1ncer. Un diagn\u00f3stico de c\u00e1ncer y su tratamiento pueden ser estresantes y provocar cambios de humor en cualquier persona. Un ejercicio adecuado, individualizado para cada persona por un fisioterapeuta, puede ayudar a reducir el estr\u00e9s y mejorar el estado de \u00e1nimo.<\/p>\n<p><strong>Niebla del cerebro.\u00a0<\/strong>El ejercicio ayuda a aliviar la confusi\u00f3n mental. Su fisioterapeuta puede dise\u00f1ar un programa individualizado de ejercicio que puede ayudar a reducir la p\u00e9rdida de memoria y la confusi\u00f3n mental.<\/p>\n<p><strong>Actividades diarias.\u00a0<\/strong>Su fisioterapeuta discutir\u00e1 con usted los objetivos de actividad y los utilizar\u00e1 para dise\u00f1ar su programa de tratamiento. Los supervivientes de c\u00e1ncer suelen aumentar su actividad f\u00edsica de forma gradual; su programa de tratamiento le ayudar\u00e1 a alcanzar sus objetivos de la forma m\u00e1s segura, r\u00e1pida y eficaz posible.<\/p>\n<p><strong>Caminando.\u00a0<\/strong>Su fisioterapeuta le ayudar\u00e1 a mejorar su capacidad para caminar utilizando t\u00e9cnicas como ejercicios de fortalecimiento, entrenamiento para caminar y actividades de equilibrio. Si tiene da\u00f1o a los nervios (neuropat\u00eda), su fisioterapeuta puede proporcionarle aparatos ortop\u00e9dicos y otras t\u00e9cnicas para que le resulte m\u00e1s f\u00e1cil o seguro caminar. Su fisioterapeuta tambi\u00e9n puede recomendarle el uso de un dispositivo de asistencia, como un andador o un bast\u00f3n.<\/p>\n<p><strong>Capacidad de entrenamiento deportivo.<\/strong>\u00a0Los atletas que reciben tratamiento contra el c\u00e1ncer pueden continuar entrenando para su deporte hasta cierto punto, seg\u00fan el tipo de c\u00e1ncer y el tratamiento. Los fisioterapeutas dise\u00f1an programas de entrenamiento seguros, desafiantes y espec\u00edficos para cada deporte para ayudar a los atletas a reducir la p\u00e9rdida de condici\u00f3n f\u00edsica y fuerza durante el tratamiento del c\u00e1ncer.<\/p>\n<p><strong>Movimiento.\u00a0<\/strong>Su fisioterapeuta elegir\u00e1 actividades y tratamientos espec\u00edficos para ayudar a restaurar el movimiento normal en las articulaciones r\u00edgidas. Estos pueden comenzar con movimientos \u201cpasivos\u201d que el fisioterapeuta realiza por usted y progresar a ejercicios activos y estiramientos que usted mismo realiza. Puede realizar estos movimientos en casa para ayudar a acelerar la curaci\u00f3n y aliviar el dolor.<\/p>\n<p><strong>Flexibilidad.\u00a0<\/strong>Su fisioterapeuta determinar\u00e1 si alg\u00fan m\u00fasculo est\u00e1 tenso, comenzar\u00e1 a ayudarlo a estirarlo y le ense\u00f1ar\u00e1 c\u00f3mo estirarlo en casa.<\/p>\n<p><strong>Fortaleza.\u00a0<\/strong>Si su fisioterapeuta encuentra m\u00fasculos d\u00e9biles o lesionados, elegir\u00e1 y le ense\u00f1ar\u00e1 los ejercicios correctos para restaurar constantemente su fuerza y agilidad.<\/p>\n<p><strong>Coordinaci\u00f3n.\u00a0<\/strong>Tu fisioterapeuta te ayudar\u00e1 a mejorar y recuperar tu coordinaci\u00f3n y agilidad, para que puedas realizar actividades dom\u00e9sticas, comunitarias y deportivas con mayor facilidad.<\/p>\n<p><strong>Balance.\u00a0<\/strong>Tu fisioterapeuta examinar\u00e1 tu equilibrio y elegir\u00e1 ejercicios espec\u00edficos que puedas realizar en la cl\u00ednica y en casa para mejorar tu equilibrio y prevenir ca\u00eddas. Su fisioterapeuta tambi\u00e9n puede ense\u00f1arle c\u00f3mo usar un bast\u00f3n o un andador para ayudarlo a mantener el equilibrio al caminar y estar de pie.<\/p>\n<p><strong>Programa de hogar.\u00a0<\/strong>Tu fisioterapeuta te ense\u00f1ar\u00e1 ejercicios de fortalecimiento, estiramiento y reducci\u00f3n del dolor para realizar en casa. Estos ejercicios estar\u00e1n dise\u00f1ados espec\u00edficamente para sus necesidades.<\/p>\n<div class=\"backTop\">\u00bfSe puede prevenir esta lesi\u00f3n o afecci\u00f3n? El riesgo de c\u00e1ncer se puede reducir mediante:<\/p>\n<ul>\n<li>Mantener una dieta saludable<\/li>\n<li>Realizar ejercicio y actividad f\u00edsica constantes durante toda la vida.<\/li>\n<li>Mantener su peso en un nivel saludable<\/li>\n<li>Evitar el tabaco en cualquier forma.<\/li>\n<li>Evitar demasiada exposici\u00f3n al sol<\/li>\n<\/ul>\n<p>Puede encontrar m\u00e1s informaci\u00f3n sobre la prevenci\u00f3n del c\u00e1ncer en el sitio web de la Sociedad Estadounidense del C\u00e1ncer.\u00a0<a href=\"https:\/\/www.cancer.org\/healthy\/otherwaystoprotectyourself\/index\" target=\"_blank\" rel=\"noopener\">sitio web<\/a>.<\/p>\n<p>Los efectos secundarios del tratamiento del c\u00e1ncer se pueden reducir o prevenir mediante:<\/p>\n<ul>\n<li>Mantenerse activo todos los d\u00edas<\/li>\n<li>Evitar demasiado reposo en cama<\/li>\n<li>Mantenerse activo y participar en actividades y ejercicios que le gusten hacer, con la mayor frecuencia y intensidad posible.<\/li>\n<\/ul>\n<p>Su fisioterapeuta puede ayudarlo a elegir los ejercicios m\u00e1s seguros y efectivos para realizar antes, durante y despu\u00e9s del tratamiento contra el c\u00e1ncer.<\/p>\n<div class=\"backTop\">Experiencias de la vida real Mary Lynn es una enfermera de 60 a\u00f1os a quien recientemente le diagnosticaron c\u00e1ncer de \u00fatero. Antes de su diagn\u00f3stico, Mary Lynn era una persona activa, trabajaba a tiempo completo en el hospital local, hac\u00eda jardiner\u00eda los fines de semana y disfrutaba de bailes de sal\u00f3n varias noches a la semana. Tambi\u00e9n le gustaba viajar y hacer ejercicio en el gimnasio de su barrio.<\/p>\n<p>Mary Lynn quer\u00eda minimizar los efectos secundarios de su tratamiento lo antes posible, por lo que se reuni\u00f3 con su fisioterapeuta despu\u00e9s de su diagn\u00f3stico y antes de la cirug\u00eda.<\/p>\n<p>El fisioterapeuta de Mary Lynn realiz\u00f3 una evaluaci\u00f3n completa de su fuerza, flexibilidad, equilibrio, sensaci\u00f3n, coordinaci\u00f3n y resistencia. Observ\u00f3 lo bien que pod\u00eda caminar, subir y bajar escaleras y sentarse y levantarse de una silla.<\/p>\n<p>Dise\u00f1\u00f3 un programa de tratamiento para abordar sus problemas espec\u00edficos, que inclu\u00edan problemas de postura, fuerza muscular y flexibilidad, p\u00e9rdida leve del equilibrio y baja resistencia. Le ense\u00f1\u00f3 ejercicios para fortalecer sus m\u00fasculos debilitados, estirarlos suavemente, recuperar el equilibrio y reconstruir su resistencia aer\u00f3bica. Mary Lynn complet\u00f3 varias sesiones con su fisioterapeuta antes de la cirug\u00eda. Se sinti\u00f3 m\u00e1s fuerte y m\u00e1s segura acerca de la cirug\u00eda debido a su mejor condici\u00f3n f\u00edsica.<\/p>\n<p>El tratamiento contra el c\u00e1ncer de Mary Lynn incluy\u00f3 histerectom\u00eda, quimioterapia y radioterapia. Continu\u00f3 recibiendo tratamientos de su fisioterapeuta despu\u00e9s de su cirug\u00eda y durante sus tratamientos de quimioterapia.<\/p>\n<p>El fisioterapeuta de Mary Lynn repiti\u00f3 su examen completo cada pocas semanas o cada vez que sent\u00eda nuevos s\u00edntomas. En cada visita, le pidi\u00f3 que describiera cualquier problema o efecto secundario actual. Examin\u00f3 su incisi\u00f3n quir\u00fargica para controlar la curaci\u00f3n. Poco despu\u00e9s de la cirug\u00eda, Mary Lynn dijo que sinti\u00f3 algunas molestias p\u00e9lvicas y que hab\u00eda experimentado algo de incontinencia. Despu\u00e9s de comenzar la quimioterapia, describi\u00f3 haber experimentado entumecimiento y ardor en los pies, y p\u00e9rdida del equilibrio al estar de pie o caminar. Tambi\u00e9n not\u00f3 que no escuchaba tan bien, hab\u00eda aumentado de peso y sent\u00eda fatiga durante todo el d\u00eda.<\/p>\n<p>El fisioterapeuta de Mary Lynn actualizaba peri\u00f3dicamente su programa de tratamiento para abordar cualquier problema nuevo. Le aplic\u00f3 una suave estimulaci\u00f3n el\u00e9ctrica en los pies para ayudar a aliviar su malestar. Le ense\u00f1\u00f3 ejercicios para fortalecer y reactivar los m\u00fasculos de su regi\u00f3n p\u00e9lvica y aliviar su dolor e incontinencia. Le dio un programa casero sencillo y f\u00e1cil para que pudiera realizar unos minutos cada d\u00eda. Mary Lynn acept\u00f3 f\u00e1cilmente el tratamiento y sigui\u00f3 con su programa hogare\u00f1o; sab\u00eda que hacerlo acelerar\u00eda su recuperaci\u00f3n.<\/p>\n<p>Con la ayuda de su fisioterapeuta, Mary Lynn mejor\u00f3 constantemente durante los siguientes meses. Ella not\u00f3 que siempre se sent\u00eda mejor despu\u00e9s de su tratamiento en la cl\u00ednica de fisioterapia y despu\u00e9s de hacer ejercicio.<\/p>\n<p>Mary Lynn pudo continuar sus entrenamientos en el gimnasio de forma modificada, durante su tratamiento contra el c\u00e1ncer, con el consejo y orientaci\u00f3n de su fisioterapeuta. Continu\u00f3 con su programa de fisioterapia y ejercicio durante toda la quimioterapia y radioterapia, y aument\u00f3 su nivel de ejercicio a sus niveles precancerosos unas pocas semanas despu\u00e9s de finalizar la quimioterapia.<\/p>\n<p>Su m\u00e9dico se alegr\u00f3 de ver cu\u00e1n activa y fuerte estaba Mary Lynn apenas unas semanas despu\u00e9s de terminar su tratamiento contra el c\u00e1ncer. Debido a que pudo mantener un buen nivel de condici\u00f3n f\u00edsica durante el tratamiento, tambi\u00e9n pudo regresar al estudio de baile de sal\u00f3n.<\/p>\n<p>\u00a1Y justo esta semana, Mary Lynn estaba orgullosa de compartir su \u00faltima cosecha de tomates y pimientos con sus vecinos!<\/p>\n<\/div>\n<p>Este art\u00edculo se public\u00f3 originalmente en el sitio web de la Asociaci\u00f3n Estadounidense de Terapia F\u00edsica. \u00a0<a href=\"https:\/\/www.moveforwardpt.com\/SymptomsConditionsDetail.aspx?cid=256fdb5e-efde-44db-bbb3-ca2d56e68b50\" target=\"_blank\" rel=\"noopener\">Haga clic aqu\u00ed para verlo.<\/a><\/p>\n<\/div>\n<\/div>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>Cancer is the growth of abnormal cells in the body that causes destruction of normal, healthy cells. This process affects the health and function of [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[41],"tags":[],"class_list":["post-1671","post","type-post","status-publish","format-standard","hentry","category-health-news-you-can-use"],"acf":[],"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/breakthrough-pt.com\/es\/wp-json\/wp\/v2\/posts\/1671","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/breakthrough-pt.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/breakthrough-pt.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/breakthrough-pt.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/breakthrough-pt.com\/es\/wp-json\/wp\/v2\/comments?post=1671"}],"version-history":[{"count":0,"href":"https:\/\/breakthrough-pt.com\/es\/wp-json\/wp\/v2\/posts\/1671\/revisions"}],"wp:attachment":[{"href":"https:\/\/breakthrough-pt.com\/es\/wp-json\/wp\/v2\/media?parent=1671"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/breakthrough-pt.com\/es\/wp-json\/wp\/v2\/categories?post=1671"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/breakthrough-pt.com\/es\/wp-json\/wp\/v2\/tags?post=1671"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}