{"id":1662,"date":"2020-06-12T12:50:02","date_gmt":"2020-06-12T12:50:02","guid":{"rendered":"https:\/\/breakthroughpt.confluentclinics.com\/blog\/chronic-pain-101\/"},"modified":"2022-11-15T20:46:04","modified_gmt":"2022-11-15T20:46:04","slug":"chronic-pain-101","status":"publish","type":"post","link":"https:\/\/breakthrough-pt.com\/es\/blog\/chronic-pain-101\/","title":{"rendered":"Dolor cr\u00f3nico 101"},"content":{"rendered":"<p>El dolor cr\u00f3nico puede ser devastador. Te preguntas si alguna vez volver\u00e1s a sentirte normal. Lo has probado todo\u2026. pastillas, quiropr\u00e1ctica, curas milagrosas, inyecciones. O pasa tiempo tratando de encontrar la soluci\u00f3n quir\u00fargica adecuada, pero nadie puede garantizar que la cirug\u00eda solucionar\u00e1 el problema e incluso podr\u00eda empeorarlo. Te preguntas si tendr\u00e1s que vivir as\u00ed para siempre.<\/p>\n<p>El dolor es complicado. Es diferente para cada ser humano y cada ser humano responde al dolor de manera diferente. El dolor agudo suele ser causado por da\u00f1o tisular. La mayor\u00eda de las veces, una vez que los tejidos sanan, el dolor desaparece. Sin embargo, para algunas personas, aunque los tejidos hayan sanado, el dolor no desaparece. El sistema nervioso se acelera y responde en exceso.\u00a0\u00a0<strong>Esto se considera dolor cr\u00f3nico.\u00a0<\/strong><\/p>\n<p>La respuesta natural de un cuerpo que sufre es cesar el movimiento, congelarse e inmovilizarse. Esto es cierto tanto para los problemas agudos como para los cr\u00f3nicos que afectan a cualquier ser humano vivo y que respira. \u00a1Y eso est\u00e1 bien! No es m\u00e1s que nuestro instinto protector que dice: &quot;Oye, eso no es seguro, \u00bfqu\u00e9 tal si juegas aqu\u00ed en la piscina para beb\u00e9s?&quot;, como si tu madre te estuviera dando una suave advertencia. Despu\u00e9s de unos d\u00edas, volvemos a nuestras tendencias y rutinas de movimiento normales. Pero en el caso de problemas cr\u00f3nicos, esa voz se vuelve m\u00e1s fuerte, como cuando tu madre dice tu primer nombre y segundo nombre en una sola advertencia. Ah\u00ed es cuando las cosas empiezan a ponerse serias. Tu cerebro simplemente est\u00e1 tratando de llamar tu atenci\u00f3n.<\/p>\n<p>El dolor cr\u00f3nico es un fen\u00f3meno muy complejo y los mejores investigadores apenas est\u00e1n empezando a comprenderlo. Por un lado, est\u00e1 John, que se rompi\u00f3 la pierna y se recuper\u00f3 f\u00e1cilmente despu\u00e9s de dos cirug\u00edas y rehabilitaci\u00f3n. Por otro lado, est\u00e1 Jane, que nunca se ha roto un hueso ni ha tenido un accidente, pero sufre un dolor de espalda cr\u00f3nico que persiste durante a\u00f1os. \u00bfPor qu\u00e9? Porque el dolor cr\u00f3nico es una experiencia, no una cuesti\u00f3n de tejido. El dolor cr\u00f3nico evoluciona debido a la sobreamplificaci\u00f3n de la respuesta de nuestro sistema nervioso a una amenaza percibida. Puede magnificarse debido al estr\u00e9s f\u00edsico en el cuerpo o incluso al estr\u00e9s emocional, como ansiedad o depresi\u00f3n con o sin lesi\u00f3n f\u00edsica real (McGonigal 2009). Algunos podr\u00edan ver esto como una mala noticia cuando este se convierta en el diagn\u00f3stico, perdiendo la esperanza de no recuperarse nunca.<\/p>\n<p>Pero hay buenas noticias.<\/p>\n<p>Debido a que experimentar dolor cr\u00f3nico es una imperfecci\u00f3n en la relaci\u00f3n mente-cuerpo, el alivio proviene del restablecimiento de esa relaci\u00f3n. Este es el momento perfecto para involucrar a un fisioterapeuta para que le ayude a dise\u00f1ar un plan de acci\u00f3n. Puede que te encuentres mezclando la terapia manual con la Realidad Virtual e incluso el yoga. Su cerebro y su cuerpo pueden volver a entrenarse para comprender una nueva normalidad.<\/p>\n<p>Los avances en neurociencia han refinado nuestra comprensi\u00f3n del dolor cr\u00f3nico y nuestros fisioterapeutas ahora incorporan intervenciones de neurociencia del dolor en el tratamiento de pacientes con dolor cr\u00f3nico.<\/p>\n<ol>\n<li>El dolor cr\u00f3nico se puede reducir, controlar o, a veces, eliminar con\u00a0<strong>educaci\u00f3n en neurociencia del dolor (PNE)<\/strong>.<\/li>\n<li>Nuestros fisioterapeutas incorporan la PNE al tratamiento de muchas maneras.<\/li>\n<li>La PNE unidireccional se puede administrar a trav\u00e9s de VR.<\/li>\n<\/ol>\n<p><strong>Planes de tratamiento personalizados de PNE\u00a0<\/strong><\/p>\n<p>Su fisioterapeuta comprende que todo dolor es real. Su fisioterapeuta puede dise\u00f1ar un plan de tratamiento dirigido espec\u00edficamente a tratar el dolor cr\u00f3nico, que \u00e9l sabe c\u00f3mo afrontar. Esto contrasta con el dolor agudo, que muchas veces tiene un prop\u00f3sito \u00fatil, como alertarnos de un peligro o de movimientos incorrectos, y es autolimitado.<\/p>\n<p>Lo primero que hacen los fisioterapeutas durante el tratamiento es realizar una evaluaci\u00f3n exhaustiva e identificar las causas y los contribuyentes al dolor del paciente. Una vez que se identifica esto y los objetivos funcionales y de movilidad del paciente est\u00e1n claros, el terapeuta dise\u00f1ar\u00e1 un plan de tratamiento que aborde espec\u00edficamente los factores que contribuyen al dolor del paciente. Suele ser una combinaci\u00f3n de ejercicio, terapia manual, manejo del estr\u00e9s, higiene del sue\u00f1o y educaci\u00f3n en neurociencia del dolor. Los nuevos avances en la tecnolog\u00eda sanitaria, como la realidad virtual, nos han permitido tratar el dolor cr\u00f3nico de manera a\u00fan m\u00e1s eficiente a trav\u00e9s de la educaci\u00f3n en neurociencia del dolor.<\/p>\n<p>Cuanto m\u00e1s ignoras el dolor, peor se vuelve. Si est\u00e1 buscando conectarse con un especialista en dolor cr\u00f3nico, nuestro equipo est\u00e1 listo para ayudarlo. Comun\u00edquese hoy para una discusi\u00f3n y evaluaci\u00f3n con nuestros fisioterapeutas para encontrar un plan de tratamiento que funcione para usted. Hemos hecho de la velocidad una prioridad con una programaci\u00f3n r\u00e1pida y sencilla.<\/p>\n<p><strong>Realidad virtual<\/strong><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-9182\" src=\"https:\/\/prorehablou.com\/wp-content\/uploads\/2020\/06\/vr-vector-1024x601.png\" alt=\"\" width=\"1024\" height=\"601\" \/><\/p>\n<p>Si no has o\u00eddo hablar de la Realidad Virtual para el tratamiento del dolor cr\u00f3nico, no te preocupes, \u00a1no est\u00e1s en una pel\u00edcula de ciencia ficci\u00f3n! La tecnolog\u00eda ha avanzado a pasos agigantados para ayudarnos a comprender nuestros cuerpos, nuestro movimiento y nuestro dolor. Piensa en esta experiencia como una versi\u00f3n de alta tecnolog\u00eda de la meditaci\u00f3n. A trav\u00e9s de los auriculares, ver\u00e1 escenas familiares: prados, la playa, una tarde tranquila, todas experiencias visualmente atractivas dise\u00f1adas para ayudarle a tomar el control del dolor con el que ha estado viviendo durante semanas, meses o a\u00f1os. Pronto descubrir\u00e1 que tiene cierto control sobre su dolor con estas t\u00e9cnicas. \u00a1Esas s\u00ed que son buenas noticias!<\/p>\n<p>Cuando use las gafas, se le presentar\u00e1n animaciones y videos dise\u00f1ados para ayudarlo a aprender, comprender y retener mejor informaci\u00f3n sobre el dolor y su percepci\u00f3n. Su fisioterapeuta integrar\u00e1 la realidad virtual en una de sus sesiones regulares de fisioterapia basada en actividades, lo que le permitir\u00e1 guiarlo a trav\u00e9s del tratamiento y monitorear continuamente su progreso.<\/p>\n<p>Este programa de vanguardia es exclusivo de nuestras cl\u00ednicas, \u00fanico en nuestra regi\u00f3n, y nuestros terapeutas han sido especialmente capacitados y certificados en educaci\u00f3n en neurociencia del dolor y tecnolog\u00eda de realidad virtual.<\/p>\n<p><strong>Yoga para el dolor cr\u00f3nico<\/strong><\/p>\n<p>El yoga trabaja para reparar esa conexi\u00f3n a trav\u00e9s de la respiraci\u00f3n, el movimiento y la conciencia, y no requiere que sudes ni te pongas de cabeza. Mediante ejercicio f\u00edsico o movimiento, el cerebro puede liberar sustancias qu\u00edmicas para suprimir el dolor f\u00edsico (Dietrich, McDaniel 2004). \u00bfQu\u00e9 es a\u00fan mejor? La atenci\u00f3n plena y la meditaci\u00f3n tambi\u00e9n pueden desempe\u00f1ar un papel en la reducci\u00f3n de futuras se\u00f1ales de dolor al calmar ese sistema de alarma demasiado amplificado, todo lo cual se puede hacer desde su casa o incluso desde la cama, y no requiere que compre los \u00faltimos pantalones de yoga.<\/p>","protected":false},"excerpt":{"rendered":"<p>Chronic pain can be devastating.\u00a0 You wonder if you\u2019ll ever feel normal again.\u00a0 You\u2019ve tried everything\u2026. pills, chiropractic, miracle cures, injections.\u00a0 Or you spend time [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":1664,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[41,61],"tags":[],"class_list":["post-1662","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-health-news-you-can-use","category-pt-over-pills"],"acf":[],"jetpack_featured_media_url":"https:\/\/breakthrough-pt.com\/wp-content\/uploads\/sites\/25\/2022\/11\/ChronicPain_Blog-1.png","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/breakthrough-pt.com\/es\/wp-json\/wp\/v2\/posts\/1662","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/breakthrough-pt.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/breakthrough-pt.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/breakthrough-pt.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/breakthrough-pt.com\/es\/wp-json\/wp\/v2\/comments?post=1662"}],"version-history":[{"count":0,"href":"https:\/\/breakthrough-pt.com\/es\/wp-json\/wp\/v2\/posts\/1662\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/breakthrough-pt.com\/es\/wp-json\/wp\/v2\/media\/1664"}],"wp:attachment":[{"href":"https:\/\/breakthrough-pt.com\/es\/wp-json\/wp\/v2\/media?parent=1662"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/breakthrough-pt.com\/es\/wp-json\/wp\/v2\/categories?post=1662"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/breakthrough-pt.com\/es\/wp-json\/wp\/v2\/tags?post=1662"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}