{"id":1641,"date":"2019-04-08T13:00:31","date_gmt":"2019-04-08T13:00:31","guid":{"rendered":"https:\/\/breakthroughpt.confluentclinics.com\/blog\/regain-control-over-incontinence\/"},"modified":"2019-04-08T13:00:31","modified_gmt":"2019-04-08T13:00:31","slug":"regain-control-over-incontinence","status":"publish","type":"post","link":"https:\/\/breakthrough-pt.com\/es\/blog\/regain-control-over-incontinence\/","title":{"rendered":"Tome el control de la incontinencia"},"content":{"rendered":"<p>Muy a menudo, nuestros pacientes se sienten solos, inc\u00f3modos, avergonzados y avergonzados cuando acuden a nosotros en busca de tratamiento para la incontinencia urinaria. Pero no tiene por qu\u00e9 ser as\u00ed: para la mayor\u00eda de las personas, es totalmente tratable y manejable, y ciertamente no est\u00e1 solo en esto.<\/p>\n<p>Seg\u00fan la Asociaci\u00f3n Nacional para la Continencia, m\u00e1s de 25 millones de personas en EE. UU. experimentan fugas de vejiga todos los d\u00edas. Y no se limita s\u00f3lo a las mujeres que han tenido hijos. Aunque las mujeres tienen el doble de probabilidades que los hombres de tener problemas de incontinencia, afecta a ambos sexos y a todas las edades. Sorprendentemente, aunque existen altas tasas de \u00e9xito asociadas con el tratamiento, s\u00f3lo 1 de cada 12 personas con incontinencia busca ayuda.<\/p>\n<h4>\u00bfQu\u00e9 es la incontinencia urinaria y por qu\u00e9 ocurre?<\/h4>\n<p>Empecemos con un poco de anatom\u00eda. Tiene m\u00fasculos del suelo p\u00e9lvico que se adhieren a la parte inferior de los huesos p\u00e9lvicos y se extienden de adelante hacia atr\u00e1s, formando una estructura similar a una hamaca que sostiene y estabiliza los huesos y \u00f3rganos de la pelvis. Cuando funcionan correctamente, estos m\u00fasculos se contraen y liberan para permitirle usar el ba\u00f1o cuando lo desee. Cuando estos m\u00fasculos no funcionan correctamente por cualquier motivo, pueden provocar fugas involuntarias y no deseadas, tambi\u00e9n conocidas como incontinencia.<\/p>\n<p>Existen algunos tipos diferentes de incontinencia urinaria, aunque hay dos que tratamos con mayor frecuencia:<\/p>\n<ul>\n<li><strong>Incontinencia de esfuerzo.<\/strong> Las personas con incontinencia de esfuerzo pueden perder orina durante cualquier tipo de movimiento, desde ejercicio o actividad f\u00edsica hasta simplemente re\u00edr, estornudar o toser. La incontinencia de esfuerzo ocurre cuando los m\u00fasculos del piso p\u00e9lvico se vuelven descoordinados, d\u00e9biles o incluso hiperactivos. Muchas veces, esta disfunci\u00f3n muscular es el resultado del embarazo o el parto, una inflamaci\u00f3n, una lesi\u00f3n o traumatismo (es decir, una fractura p\u00e9lvica), la edad o incluso la falta de ejercicio regular.<\/li>\n<li><strong>Incontinencia de urgencia.<\/strong> Las personas con incontinencia de urgencia experimentan una repentina y fuerte necesidad de &quot;ir&quot; y, a menudo, gotean antes de poder llegar al ba\u00f1o. Al igual que en la incontinencia de esfuerzo, los pacientes con incontinencia de urgencia a menudo pueden perder el control sobre los m\u00fasculos del suelo p\u00e9lvico como resultado de la debilidad. Pero tambi\u00e9n puede ser el resultado de tensi\u00f3n muscular o espasmos que contribuyen a las contracciones incontroladas de la vejiga. La incontinencia de urgencia tambi\u00e9n puede ser el resultado de la ansiedad, el tabaquismo, los malos h\u00e1bitos urinarios o el consumo de alimentos que inflaman el revestimiento de la vejiga, como la cafe\u00edna y el az\u00facar.<\/li>\n<\/ul>\n<p>Algunos pacientes pueden experimentar tanto incontinencia de esfuerzo como de urgencia.<\/p>\n<h4>Tengo incontinencia. \u00bfQu\u00e9 har\u00e1 mi fisioterapeuta en mi evaluaci\u00f3n inicial?<\/h4>\n<p>Primero, un fisioterapeuta, experto en el tratamiento de la incontinencia y otras disfunciones de la salud p\u00e9lvica, identificar\u00e1 las causas de su incontinencia urinaria y le pedir\u00e1 que describa sus s\u00edntomas, sus experiencias cotidianas y cualquier comportamiento que pueda empeorar los s\u00edntomas. Evaluar\u00e1n los m\u00fasculos del suelo p\u00e9lvico, la cadera y la espalda baja para determinar su coordinaci\u00f3n, fuerza y flexibilidad. Su fisioterapeuta tambi\u00e9n puede enviarlo a casa con un diario de la vejiga para realizar un seguimiento de los factores de comportamiento que tambi\u00e9n contribuyen a sus s\u00edntomas.<\/p>\n<h4>\u00bfC\u00f3mo ser\u00e1 mi plan de tratamiento?<\/h4>\n<p>Eso depende de los resultados de su evaluaci\u00f3n inicial: no es una soluci\u00f3n \u00fanica para todos. Su fisioterapeuta crear\u00e1 un programa de tratamiento especializado que tenga en cuenta sus fortalezas, debilidades y objetivos espec\u00edficos.<\/p>\n<p>Su plan de tratamiento incluir\u00e1 ejercicios dise\u00f1ados para ayudarle a contraer y relajar los m\u00fasculos del suelo p\u00e9lvico, fortalecerlos y reentrenarlos y, a su vez, ayudarle a controlar mejor su vejiga. Su fisioterapeuta tambi\u00e9n puede brindarle consejos diet\u00e9ticos para ayudarlo a evitar alimentos y bebidas que puedan irritar la vejiga.<\/p>\n<h4>\u00bfListo para recuperar el control?<\/h4>\n<p>\u00a1Estamos aqu\u00ed para ayudar! <strong><a href=\"https:\/\/breakthrough-pt.com\/es\/services\/pelvic-health\/\">haga clic aqu\u00ed<\/a><\/strong> para conocer a nuestros especialistas en salud p\u00e9lvica, o <strong><a href=\"https:\/\/breakthrough-pt.com\/es\/for-patients\/schedule-an-appointment\/\">aqu\u00ed para programar una cita<\/a><\/strong> hoy.<\/p>","protected":false},"excerpt":{"rendered":"<p>So often, our patients feel alone, awkward, ashamed, and embarrassed when they come to us seeking treatment for urinary incontinence. But it doesn\u2019t have to [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[41],"tags":[],"class_list":["post-1641","post","type-post","status-publish","format-standard","hentry","category-health-news-you-can-use"],"acf":[],"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/breakthrough-pt.com\/es\/wp-json\/wp\/v2\/posts\/1641","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/breakthrough-pt.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/breakthrough-pt.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/breakthrough-pt.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/breakthrough-pt.com\/es\/wp-json\/wp\/v2\/comments?post=1641"}],"version-history":[{"count":0,"href":"https:\/\/breakthrough-pt.com\/es\/wp-json\/wp\/v2\/posts\/1641\/revisions"}],"wp:attachment":[{"href":"https:\/\/breakthrough-pt.com\/es\/wp-json\/wp\/v2\/media?parent=1641"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/breakthrough-pt.com\/es\/wp-json\/wp\/v2\/categories?post=1641"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/breakthrough-pt.com\/es\/wp-json\/wp\/v2\/tags?post=1641"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}