{"id":1499,"date":"2016-03-07T17:40:21","date_gmt":"2016-03-07T17:40:21","guid":{"rendered":"https:\/\/breakthroughpt.confluentclinics.com\/blog\/did-you-know-physical-activity-plays-a-greater-role-in-obesity-than-caloric-intake\/"},"modified":"2022-11-15T20:44:03","modified_gmt":"2022-11-15T20:44:03","slug":"did-you-know-physical-activity-plays-a-greater-role-in-obesity-than-caloric-intake","status":"publish","type":"post","link":"https:\/\/breakthrough-pt.com\/es\/blog\/did-you-know-physical-activity-plays-a-greater-role-in-obesity-than-caloric-intake\/","title":{"rendered":"\u00bfSab\u00edas? La actividad f\u00edsica desempe\u00f1a un papel m\u00e1s importante en la obesidad que la ingesta cal\u00f3rica"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\"alignright  wp-image-1836\" src=\"https:\/\/breakthrough-pt.com\/wp-content\/uploads\/sites\/25\/2022\/11\/6f405a5214f4fc791318239ac877167b.jpg\" alt=\"6f405a5214f4fc791318239ac877167b\" width=\"336\" height=\"336\" \/><\/p>\n<p>Seg\u00fan un nuevo estudio, la actividad f\u00edsica, no la ingesta cal\u00f3rica, es el resultado final de lo que le sucede a la cintura.<\/p>\n<p>Seg\u00fan un art\u00edculo de agosto de 2014 publicado en el\u00a0<em>Revista Americana de Medicina<\/em>, &#8220;<a href=\"https:\/\/www.amjmed.com\/article\/S0002-9343%2814%2900191-0\/abstract\" target=\"_blank\" rel=\"noopener noreferrer\">Obesidad, obesidad abdominal, actividad f\u00edsica e ingesta cal\u00f3rica en adultos estadounidenses: 1988 a 2010<\/a>\u201d, los investigadores encontraron que si bien las tasas de obesidad aumentaron, la ingesta cal\u00f3rica \u201cno cambi\u00f3 significativamente con el tiempo para las mujeres o los hombres en su conjunto, o cuando se estratific\u00f3 por raza\/etnia\u201d. Sin embargo, el n\u00famero de estadounidenses que informaron no realizar ninguna actividad f\u00edsica durante su tiempo libre se triplic\u00f3, de 15,31 TP3T a 47,61 TP3T.<\/p>\n<p>Los autores creen que los resultados prestan m\u00e1s apoyo a la\u00a0<a href=\"https:\/\/www.iom.edu\/\" target=\"_blank\" rel=\"noopener noreferrer\">Instituto de Medicina<\/a>los esfuerzos de vincular la actividad f\u00edsica con la reducci\u00f3n de la obesidad. La Asociaci\u00f3n Estadounidense de Terapia F\u00edsica apoya firmemente la promoci\u00f3n de la actividad f\u00edsica y el valor del buen estado f\u00edsico para prevenir la obesidad.<\/p>\n<p><strong>Recursos Relacionados:<\/strong><\/p>\n<ul>\n<li><a href=\"https:\/\/www.moveforwardpt.com\/DidYouKnow\/Detail.aspx?cid=78008fe2-5259-42a2-abd4-1911131c59f1#.U6giPJRdWSo\" target=\"_blank\" rel=\"noopener noreferrer\">\u00bfSab\u00eda que la obesidad puede representar el 18% de las muertes de adultos en EE. UU.?<\/a><\/li>\n<li><a href=\"https:\/\/www.moveforwardpt.com\/DidYouKnow\/Detail.aspx?cid=07275db7-891a-497a-ad9d-6b35da5d6811#.VK7UcsnuqQc\" target=\"_blank\" rel=\"noopener noreferrer\">\u00bfSab\u00eda que las vacaciones de verano est\u00e1n relacionadas con el aumento de peso en los ni\u00f1os?<\/a><\/li>\n<li><a href=\"https:\/\/www.moveforwardpt.com\/SymptomsConditionsDetail.aspx?cid=df77f3aa-573b-4d1e-893b-18c88e6cedce#.VK7iGcnuqQc\" target=\"_blank\" rel=\"noopener noreferrer\">Gu\u00eda del fisioterapeuta sobre la obesidad<\/a><\/li>\n<\/ul>\n<p>Este art\u00edculo se public\u00f3 originalmente en el sitio web de la Asociaci\u00f3n Estadounidense de Terapia F\u00edsica (APTA) y esta foto es cortes\u00eda de la APTA. \u00a0<a href=\"https:\/\/www.moveforwardpt.com\/DidYouKnow\/Detail.aspx?cid=f8ae4198-da04-42fe-8ab9-48d20d8f5891\" target=\"_blank\" rel=\"noopener\">Haga clic aqu\u00ed para verlo. <\/a><\/p>","protected":false},"excerpt":{"rendered":"<p>Physical activity, not caloric intake, is the bottom line about what happens to your waistline, according to a new study. According to an August 2014 [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":1500,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[41],"tags":[],"class_list":["post-1499","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-health-news-you-can-use"],"acf":[],"jetpack_featured_media_url":"https:\/\/breakthrough-pt.com\/wp-content\/uploads\/sites\/25\/2022\/11\/6f405a5214f4fc791318239ac877167b.jpg","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/breakthrough-pt.com\/es\/wp-json\/wp\/v2\/posts\/1499","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/breakthrough-pt.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/breakthrough-pt.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/breakthrough-pt.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/breakthrough-pt.com\/es\/wp-json\/wp\/v2\/comments?post=1499"}],"version-history":[{"count":0,"href":"https:\/\/breakthrough-pt.com\/es\/wp-json\/wp\/v2\/posts\/1499\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/breakthrough-pt.com\/es\/wp-json\/wp\/v2\/media\/1500"}],"wp:attachment":[{"href":"https:\/\/breakthrough-pt.com\/es\/wp-json\/wp\/v2\/media?parent=1499"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/breakthrough-pt.com\/es\/wp-json\/wp\/v2\/categories?post=1499"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/breakthrough-pt.com\/es\/wp-json\/wp\/v2\/tags?post=1499"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}